{"id":1356,"date":"2024-03-04T00:42:32","date_gmt":"2024-03-04T00:42:32","guid":{"rendered":"https:\/\/usesuretox.info\/cb\/?post_type=portfolio&#038;p=1356"},"modified":"2026-06-11T22:20:11","modified_gmt":"2026-06-11T22:20:11","slug":"all-insect-killer","status":"publish","type":"portfolio","link":"https:\/\/usesuretox.info\/cb\/portfolio-item\/all-insect-killer\/","title":{"rendered":"All Insect Killer"},"content":{"rendered":"<div id='av_section_1'  class='avia-section av-6xgak-ef0490d14e5d50da58e0906f6b57ff26 main_color avia-section-default avia-no-shadow  avia-builder-el-0  avia-builder-el-no-sibling  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1356'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6e75s-513296cca11eaeabc1ba12e522142af1\">\n.flex_column.av-6e75s-513296cca11eaeabc1ba12e522142af1{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-6e75s-513296cca11eaeabc1ba12e522142af1 av_one_half  avia-builder-el-1  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l9ms-aae50d3817aa6df66374dcded0abba05\">\n#top .av-special-heading.av-l9ms-aae50d3817aa6df66374dcded0abba05{\npadding-bottom:10px;\ncolor:#0018a8;\n}\nbody .av-special-heading.av-l9ms-aae50d3817aa6df66374dcded0abba05 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-l9ms-aae50d3817aa6df66374dcded0abba05 .special-heading-inner-border{\nborder-color:#0018a8;\n}\n.av-special-heading.av-l9ms-aae50d3817aa6df66374dcded0abba05 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-l9ms-aae50d3817aa6df66374dcded0abba05 av-special-heading-h2 custom-color-heading blockquote modern-quote  avia-builder-el-2  el_before_av_iconlist  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Super Suretox &#8211; All Insect Killer<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  class='avia-icon-list-container av-50pzk-f710c41fd6c0f55789ac3dcfa5fa8955  avia-builder-el-3  el_after_av_heading  el_before_av_image '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-big av-50pzk-f710c41fd6c0f55789ac3dcfa5fa8955 avia-iconlist-animate'>\n<li><div class='iconlist_icon av-4b98s-c98adb5d2e5e4cafec625a09015e9350 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue812' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >Combined power<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-44m78-5784e3aa380818edd9d49432cc8f80b9 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue812' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >Kills crawling insects on contact and knocks down flying insects rapidly. <\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-35faw-741358cee7ec2f07b6efdac9b328ebd0 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue812' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >Fresh scent<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-2svzo-604e8d99cce66e72b35a7618a4b5524e avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue812' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >Sizes: 250ml, 400ml, and 600ml<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<li><div class='iconlist_icon av-2svzo-1-c9837fd6ff564b6c1b1f16056cad8b89 avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue812' data-av_iconfont='entypo-fontello'><\/span><\/div><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >Active Ingredients: Piperonyl Butoxide, Tetramethrin, Cypermethrin, Sumithrin<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mqa21boa-998933c232a57764cff40bcfd14ff053\">\n.avia-image-container.av-mqa21boa-998933c232a57764cff40bcfd14ff053 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-mqa21boa-998933c232a57764cff40bcfd14ff053 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-mqa21boa-998933c232a57764cff40bcfd14ff053 av-styling- avia-align-left  avia-builder-el-4  el_after_av_iconlist  avia-builder-el-last '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"http:\/\/www.usesuretox.info\/cb\/wp-content\/uploads\/msds_sheets\/Suretox_AIK_SDS.pdf\" class='avia_image' ><img decoding=\"async\" class='wp-image-1407 avia-img-lazy-loading-not-1407 avia_image ' src=\"https:\/\/usesuretox.info\/cb\/wp-content\/uploads\/2024\/03\/msds-download.png\" alt='' title='msds-download'  height=\"46\" width=\"120\"  itemprop=\"thumbnailUrl\"  \/><\/a><\/div><\/div><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1ibr8-006387ce97de2edd84185081cea972c4\">\n.flex_column.av-1ibr8-006387ce97de2edd84185081cea972c4{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1ibr8-006387ce97de2edd84185081cea972c4 av_one_half  avia-builder-el-5  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-y37g-1af997d0d2a6ec8c17afe924bf238e6b\">\n.avia-image-container.av-y37g-1af997d0d2a6ec8c17afe924bf238e6b img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-y37g-1af997d0d2a6ec8c17afe924bf238e6b .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-y37g-1af997d0d2a6ec8c17afe924bf238e6b av-styling- avia-align-center  avia-builder-el-6  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-86 avia-img-lazy-loading-not-86 avia_image ' src=\"https:\/\/usesuretox.info\/cb\/wp-content\/uploads\/2024\/03\/all-insect-killer-495x400.png\" alt='' title='all-insect-killer'  height=\"400\" width=\"495\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div><\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1356'><div class='entry-content-wrapper clearfix'>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":277,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"portfolio_entries":[6],"_links":{"self":[{"href":"https:\/\/usesuretox.info\/cb\/wp-json\/wp\/v2\/portfolio\/1356"}],"collection":[{"href":"https:\/\/usesuretox.info\/cb\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/usesuretox.info\/cb\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/usesuretox.info\/cb\/wp-json\/wp\/v2\/comments?post=1356"}],"version-history":[{"count":7,"href":"https:\/\/usesuretox.info\/cb\/wp-json\/wp\/v2\/portfolio\/1356\/revisions"}],"predecessor-version":[{"id":1406,"href":"https:\/\/usesuretox.info\/cb\/wp-json\/wp\/v2\/portfolio\/1356\/revisions\/1406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/usesuretox.info\/cb\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/usesuretox.info\/cb\/wp-json\/wp\/v2\/media?parent=1356"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/usesuretox.info\/cb\/wp-json\/wp\/v2\/tags?post=1356"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/usesuretox.info\/cb\/wp-json\/wp\/v2\/portfolio_entries?post=1356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}